{"id":90,"date":"2021-12-22T18:47:55","date_gmt":"2021-12-22T17:47:55","guid":{"rendered":"http:\/\/naturyoga.com\/?page_id=90"},"modified":"2026-01-26T12:45:28","modified_gmt":"2026-01-26T11:45:28","slug":"contact","status":"publish","type":"page","link":"https:\/\/naturyoga.com\/en\/contact\/","title":{"rendered":"CONTACT US"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"90\" class=\"elementor elementor-90\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb7f7cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb7f7cc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f8bac6\" data-id=\"0f8bac6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92a61ce elementor-widget elementor-widget-spacer\" data-id=\"92a61ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e76c8af elementor-widget elementor-widget-heading\" data-id=\"e76c8af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Contacta con NaturYoga<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d6548e elementor-widget elementor-widget-heading\" data-id=\"8d6548e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Estamos Aqu\u00ed para Ayudarte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-524dc64 elementor-widget elementor-widget-spacer\" data-id=\"524dc64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78e5f9d elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"78e5f9d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-92d57ec\" data-id=\"92d57ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccc6987 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccc6987\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0ed9f9\" data-id=\"e0ed9f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32d6483 elementor-widget elementor-widget-spacer\" data-id=\"32d6483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8b3ad4c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b3ad4c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7cd0f30\" data-id=\"7cd0f30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-50baeea\" data-id=\"50baeea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e50651 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"9e50651\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"33\" height=\"24\" src=\"https:\/\/naturyoga.com\/wp-content\/uploads\/mail.icon_.png\" class=\"attachment-full size-full wp-image-498\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">info@naturyoga.com<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-de4ed85\" data-id=\"de4ed85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa5afbf elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"fa5afbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"34\" height=\"34\" src=\"https:\/\/naturyoga.com\/wp-content\/uploads\/fb-icon.png\" class=\"attachment-full size-full wp-image-499\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">naturyoga.offical<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-704fe74\" data-id=\"704fe74\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dcf2c60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dcf2c60\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-10be93d\" data-id=\"10be93d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d2b7ac3\" data-id=\"d2b7ac3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2d0886 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"f2d0886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"33\" height=\"33\" src=\"https:\/\/naturyoga.com\/wp-content\/uploads\/phone-icon.png\" class=\"attachment-full size-full wp-image-503\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">+34 678 887 638<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5ced78f\" data-id=\"5ced78f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9a536c elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"c9a536c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"33\" height=\"33\" src=\"https:\/\/naturyoga.com\/wp-content\/uploads\/insta-icon.png\" class=\"attachment-full size-full wp-image-507\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">@naturyoga.official<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5a48d79\" data-id=\"5a48d79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f941c23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f941c23\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4b40ce\" data-id=\"f4b40ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2cefb9 elementor-widget elementor-widget-spacer\" data-id=\"c2cefb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b70deb5 elementor-widget elementor-widget-heading\" data-id=\"b70deb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">d\u00e9janos tu mensaje<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dff1199 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dff1199\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2c9f14\" data-id=\"a2c9f14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de39064 eael-contact-form-7-button-align-left eael-contact-form-7-button-custom elementor-widget elementor-widget-eael-contact-form-7\" data-id=\"de39064\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eael-contact-form-7-wrapper\">\n                <div class=\"eael-contact-form eael-contact-form-7 eael-contact-form-de39064 placeholder-show eael-contact-form-align-left\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f497-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"497\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/90#wpcf7-f497-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/90#wpcf7-f497-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"497\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f497-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label> First Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> E-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Subject<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n<\/p>\n<p><label> Tu mensaje (opcional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-474\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-474\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I accept <a href=\"https:\/\/naturyoga.com\/en\/privacy-policy\/\" rel=\"nofollow\" target=\"_blank\"> privacy policy<\/a><\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div>\n            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-216fe6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"216fe6f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e620389\" data-id=\"e620389\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1536c2 elementor-widget elementor-widget-spacer\" data-id=\"d1536c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-866b636 elementor-widget elementor-widget-heading\" data-id=\"866b636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">faqs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a84b89f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a84b89f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a46246\" data-id=\"1a46246\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9414ec9 elementor-widget elementor-widget-image\" data-id=\"9414ec9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"692\" src=\"https:\/\/naturyoga.com\/wp-content\/uploads\/122338806_s_bgr.png\" class=\"attachment-large size-large wp-image-524\" alt=\"\" srcset=\"https:\/\/naturyoga.com\/wp-content\/uploads\/122338806_s_bgr.png 692w, https:\/\/naturyoga.com\/wp-content\/uploads\/122338806_s_bgr-300x300.png 300w, https:\/\/naturyoga.com\/wp-content\/uploads\/122338806_s_bgr-150x150.png 150w, https:\/\/naturyoga.com\/wp-content\/uploads\/122338806_s_bgr-600x600.png 600w, https:\/\/naturyoga.com\/wp-content\/uploads\/122338806_s_bgr-100x100.png 100w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-160ca14\" data-id=\"160ca14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90b0cc6 elementor-widget elementor-widget-heading\" data-id=\"90b0cc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfTengo que registrarme para comprar en naturyoga.com?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-595c9f9 elementor-widget elementor-widget-text-editor\" data-id=\"595c9f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No es necesario que te registres para realizar tu compra en naturyoga.com, cuando vayas a comenzar el proceso de pago selecciona la opci\u00f3n de \u201ccomprar como invitado\u201d y no tendr\u00e1s que crearte un usuario para realizar tu pedido.<\/p><p>Tambi\u00e9n existe la opci\u00f3n de registrarte, de esta forma ser\u00e1 m\u00e1s f\u00e1cil para ti realizar compras futuras y encima disfrutar\u00e1s de algunas ventajas exclusivas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae488ad elementor-widget elementor-widget-heading\" data-id=\"ae488ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1nto cuestan los gastos de env\u00edo?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96b5e46 elementor-widget elementor-widget-text-editor\" data-id=\"96b5e46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para pedidos inferiores a 25\u20ac, los gastos de env\u00edo se calculan aparte. Si haces un pedido de m\u00e1s de 25\u20ac, tus gastos de env\u00edo ser\u00e1n gratuitos en pen\u00ednsula de Espa\u00f1a!<\/p><p>Si deseas recibir el pedido en Islas Baleares, cont\u00e1ctanos por correo electr\u00f3nico, tel\u00e9fono o WhatsApp.<\/p><p>Si quieres recibir tu pedido en una zona diferente a las que hemos mencionado, ponte en contacto con nosotros rellenando el formulario, mandando un mail a <a href=\"mailto:marketing@naturyoga.com\">marketing@naturyoga.com<\/a> o llamando al 678 887 638.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9aa5fc3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9aa5fc3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-752bb2d\" data-id=\"752bb2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c81d622 elementor-widget elementor-widget-heading\" data-id=\"c81d622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1nto tiempo tarda la entrega?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7ef60f elementor-widget elementor-widget-text-editor\" data-id=\"c7ef60f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tardamos hasta 24 horas laborales en preparar tu pedido. El env\u00edo puede tardar hasta 72 horas laborales en Pen\u00ednsula de Espa\u00f1a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82c2851 elementor-widget elementor-widget-heading\" data-id=\"82c2851\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 garant\u00edas ofrec\u00e9is?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dca56f3 elementor-widget elementor-widget-text-editor\" data-id=\"dca56f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Garant\u00eda de transporte: todos nuestros env\u00edos viajan cubiertos por un seguro del 100% del valor de la mercanc\u00eda. En el caso de que tu pedido llegue da\u00f1ado, dispones de un plazo de 24 horas para efectuar una reclamaci\u00f3n.<\/p>\n<p>Garant\u00eda del producto: esta garant\u00eda cubre defectos producidos por la fabricaci\u00f3n. Si descubres que alguno de los productos que has recibido tiene un defecto de f\u00e1brica, dispones de 14 d\u00edas naturales para presentar una reclamaci\u00f3n.<\/p>\n<p>Si tienes que hacer uso de cualquiera de las dos garant\u00edas, ponte en contacto con nosotros rellenando el formulario de contacto, mandando un mail a <a href=\"mailto:marketing@naturyoga.com\">marketing@naturyoga.com<\/a> o llamando al 678 887 638. \u00a1Estamos encantados de atenderte!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b588543\" data-id=\"b588543\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a99bb90 elementor-widget elementor-widget-image\" data-id=\"a99bb90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"692\" height=\"692\" src=\"https:\/\/naturyoga.com\/wp-content\/uploads\/134260119_s_bgr.png\" class=\"attachment-large size-large wp-image-530\" alt=\"\" srcset=\"https:\/\/naturyoga.com\/wp-content\/uploads\/134260119_s_bgr.png 692w, https:\/\/naturyoga.com\/wp-content\/uploads\/134260119_s_bgr-300x300.png 300w, https:\/\/naturyoga.com\/wp-content\/uploads\/134260119_s_bgr-150x150.png 150w, https:\/\/naturyoga.com\/wp-content\/uploads\/134260119_s_bgr-600x600.png 600w, https:\/\/naturyoga.com\/wp-content\/uploads\/134260119_s_bgr-100x100.png 100w\" sizes=\"(max-width: 692px) 100vw, 692px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2100c27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2100c27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c3f2c08\" data-id=\"c3f2c08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-003b35c elementor-widget elementor-widget-spacer\" data-id=\"003b35c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Contacta con NaturYoga Estamos Aqu\u00ed para Ayudarte info@naturyoga.com naturyoga.offical +34 678 887 638 @naturyoga.official d\u00e9janos tu mensaje Tu nombre Tu correo electr\u00f3nico Asunto Tu mensaje (opcional) Acepto la pol\u00edtica de privacidad faqs \u00bfTengo que registrarme para comprar en naturyoga.com? No es necesario que te registres para realizar tu compra en naturyoga.com, cuando vayas a comenzar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-90","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contacto | NaturYoga<\/title>\n<meta name=\"description\" content=\"Cont\u00e1ctanos para m\u00e1s informaci\u00f3n sobre material de yoga. Estamos aqu\u00ed para ayudarte con nuestros productos de yoga. Precio especial para Centros de yoga\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/naturyoga.com\/en\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacto | NaturYoga\" \/>\n<meta property=\"og:description\" content=\"Cont\u00e1ctanos para m\u00e1s informaci\u00f3n sobre material de yoga. Estamos aqu\u00ed para ayudarte con nuestros productos de yoga. Precio especial para Centros de yoga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/naturyoga.com\/en\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Naturyoga\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T11:45:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/naturyoga.com\/wp-content\/uploads\/mail.icon_.png\" \/>\n\t<meta property=\"og:image:width\" content=\"33\" \/>\n\t<meta property=\"og:image:height\" content=\"24\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/naturyoga.com\\\/contact\\\/\",\"url\":\"https:\\\/\\\/naturyoga.com\\\/contact\\\/\",\"name\":\"Contacto | NaturYoga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/naturyoga.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/naturyoga.com\\\/contact\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/naturyoga.com\\\/contact\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/naturyoga.com\\\/wp-content\\\/uploads\\\/mail.icon_.png\",\"datePublished\":\"2021-12-22T17:47:55+00:00\",\"dateModified\":\"2026-01-26T11:45:28+00:00\",\"description\":\"Cont\u00e1ctanos para m\u00e1s informaci\u00f3n sobre material de yoga. Estamos aqu\u00ed para ayudarte con nuestros productos de yoga. Precio especial para Centros de yoga\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/naturyoga.com\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/naturyoga.com\\\/contact\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/naturyoga.com\\\/contact\\\/#primaryimage\",\"url\":\"https:\\\/\\\/naturyoga.com\\\/wp-content\\\/uploads\\\/mail.icon_.png\",\"contentUrl\":\"https:\\\/\\\/naturyoga.com\\\/wp-content\\\/uploads\\\/mail.icon_.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/naturyoga.com\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/naturyoga.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONTACTO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/naturyoga.com\\\/#website\",\"url\":\"https:\\\/\\\/naturyoga.com\\\/\",\"name\":\"Naturyoga\",\"description\":\"Productos de Yoga: esterillas, bloques, silla Iyengar, rueda de Yoga, mantas\",\"publisher\":{\"@id\":\"https:\\\/\\\/naturyoga.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/naturyoga.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/naturyoga.com\\\/#organization\",\"name\":\"naturyoga\",\"url\":\"https:\\\/\\\/naturyoga.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/naturyoga.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/naturyoga.com\\\/wp-content\\\/uploads\\\/Logo-small.png\",\"contentUrl\":\"https:\\\/\\\/naturyoga.com\\\/wp-content\\\/uploads\\\/Logo-small.png\",\"width\":128,\"height\":48,\"caption\":\"naturyoga\"},\"image\":{\"@id\":\"https:\\\/\\\/naturyoga.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contacto | NaturYoga","description":"Cont\u00e1ctanos para m\u00e1s informaci\u00f3n sobre material de yoga. Estamos aqu\u00ed para ayudarte con nuestros productos de yoga. Precio especial para Centros de yoga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/naturyoga.com\/en\/contact\/","og_locale":"en_GB","og_type":"article","og_title":"Contacto | NaturYoga","og_description":"Cont\u00e1ctanos para m\u00e1s informaci\u00f3n sobre material de yoga. Estamos aqu\u00ed para ayudarte con nuestros productos de yoga. Precio especial para Centros de yoga","og_url":"https:\/\/naturyoga.com\/en\/contact\/","og_site_name":"Naturyoga","article_modified_time":"2026-01-26T11:45:28+00:00","og_image":[{"width":33,"height":24,"url":"https:\/\/naturyoga.com\/wp-content\/uploads\/mail.icon_.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/naturyoga.com\/contact\/","url":"https:\/\/naturyoga.com\/contact\/","name":"Contacto | NaturYoga","isPartOf":{"@id":"https:\/\/naturyoga.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/naturyoga.com\/contact\/#primaryimage"},"image":{"@id":"https:\/\/naturyoga.com\/contact\/#primaryimage"},"thumbnailUrl":"https:\/\/naturyoga.com\/wp-content\/uploads\/mail.icon_.png","datePublished":"2021-12-22T17:47:55+00:00","dateModified":"2026-01-26T11:45:28+00:00","description":"Cont\u00e1ctanos para m\u00e1s informaci\u00f3n sobre material de yoga. Estamos aqu\u00ed para ayudarte con nuestros productos de yoga. Precio especial para Centros de yoga","breadcrumb":{"@id":"https:\/\/naturyoga.com\/contact\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/naturyoga.com\/contact\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/naturyoga.com\/contact\/#primaryimage","url":"https:\/\/naturyoga.com\/wp-content\/uploads\/mail.icon_.png","contentUrl":"https:\/\/naturyoga.com\/wp-content\/uploads\/mail.icon_.png"},{"@type":"BreadcrumbList","@id":"https:\/\/naturyoga.com\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/naturyoga.com\/"},{"@type":"ListItem","position":2,"name":"CONTACTO"}]},{"@type":"WebSite","@id":"https:\/\/naturyoga.com\/#website","url":"https:\/\/naturyoga.com\/","name":"Naturyoga","description":"Productos de Yoga: esterillas, bloques, silla Iyengar, rueda de Yoga, mantas","publisher":{"@id":"https:\/\/naturyoga.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/naturyoga.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/naturyoga.com\/#organization","name":"naturyoga","url":"https:\/\/naturyoga.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/naturyoga.com\/#\/schema\/logo\/image\/","url":"https:\/\/naturyoga.com\/wp-content\/uploads\/Logo-small.png","contentUrl":"https:\/\/naturyoga.com\/wp-content\/uploads\/Logo-small.png","width":128,"height":48,"caption":"naturyoga"},"image":{"@id":"https:\/\/naturyoga.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/pages\/90","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/comments?post=90"}],"version-history":[{"count":16,"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/pages\/90\/revisions"}],"predecessor-version":[{"id":6290,"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/pages\/90\/revisions\/6290"}],"wp:attachment":[{"href":"https:\/\/naturyoga.com\/en\/wp-json\/wp\/v2\/media?parent=90"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}